{"id":1624,"date":"2019-04-28T16:00:28","date_gmt":"2019-04-28T14:00:28","guid":{"rendered":"https:\/\/www.pace-europe.eu\/?p=1624"},"modified":"2019-04-28T17:14:36","modified_gmt":"2019-04-28T15:14:36","slug":"pace-109-propositions-pour-leurope","status":"publish","type":"post","link":"https:\/\/www.pace-europe.eu\/ro\/2019\/04\/28\/pace-109-propositions-pour-leurope\/","title":{"rendered":"PACE : 109 propositions pour l&#8217;Europe"},"content":{"rendered":"\n<p>Le 18 avril dernier, Audric Alexandre, t\u00eate de liste aux prochaines \u00e9lections europ\u00e9ennes, Philippe Mazuel, pr\u00e9sident de PACE, David Mongin, Fabienne Lottin, Marl\u00e8ne Sgard et Bruno Gambey ont pr\u00e9sent\u00e9 le <a rel=\"noreferrer noopener\" aria-label=\"programme (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.pace-europe.eu\/wp-content\/uploads\/2019\/04\/Programme-europeennePACE-2019.pdf\" target=\"_blank\">programme<\/a> de PACE \u00e0 Abbeville. <\/p>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-vivid-cyan-blue-color\">Cliquez <a href=\"http:\/\/www.courrier-picard.fr\/178507\/article\/2019-04-18\/le-parti-des-citoyens-europeens-fait-109-propositions-pour-leurope\"><strong><em>ici<\/em><\/strong><\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 18 avril dernier, Audric Alexandre, t\u00eate de liste aux prochaines \u00e9lections europ\u00e9ennes, Philippe Mazuel, pr\u00e9sident de PACE, David Mongin, Fabienne Lottin, Marl\u00e8ne Sgard et Bruno Gambey ont pr\u00e9sent\u00e9 le programme de PACE \u00e0 Abbeville. Cliquez ici<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[22,14,10,17,24,11,15,23,21,20],"_links":{"self":[{"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/posts\/1624"}],"collection":[{"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/comments?post=1624"}],"version-history":[{"count":1,"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/posts\/1624\/revisions"}],"predecessor-version":[{"id":1625,"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/posts\/1624\/revisions\/1625"}],"wp:attachment":[{"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/media?parent=1624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/categories?post=1624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pace-europe.eu\/ro\/wp-json\/wp\/v2\/tags?post=1624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}